{"id":153874,"date":"2026-02-04T12:34:44","date_gmt":"2026-02-04T11:34:44","guid":{"rendered":"https:\/\/www.cafbl.cat\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/"},"modified":"2026-02-23T12:52:14","modified_gmt":"2026-02-23T11:52:14","slug":"cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara","status":"publish","type":"post","link":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/","title":{"rendered":"Cuando prescribe la deuda de un vecino moroso: la ley en Catalu\u00f1a no es clara"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"153874\" class=\"elementor elementor-153874 elementor-153859\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed910 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ed910\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66d61f6e elementor-widget elementor-widget-text-editor\" data-id=\"66d61f6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Barcelona, 4 de febrero del 2026<\/p>\n<p><strong>Un vecino moroso<\/strong> es la pesadilla de las comunidades de propietarios, porque <strong>la deuda recae en la comunidad<\/strong> y puede llegar a ser muy alto.<\/p>\n<p>La comunidad de vecinos puede acabar demandando el propietario que no paga, pero hay que tener cuidado con los plazos, porque <strong>la deuda prescribe en el ninguno de unos a\u00f1os.<\/strong><\/p>\n<p>Una <a href=\"https:\/\/www.poderjudicial.es\/search\/AN\/openDocument\/2c9f4a42721d667fa0a8778d75e36f0d\/20251205\">sentencia reciente del Tribunal Supremo<\/a> fija en <strong>5 a\u00f1os<\/strong> la prescripci\u00f3n de las deudas en una comunidad de vecinos, pero <strong>en Catalu\u00f1a este plazo puede ser diferente.<\/strong><\/p>\n<p>\u00abEn Catalu\u00f1a tenemos normativa y jurisdicci\u00f3n propia, esto quiere decir que la sentencia del Tribunal Supremo no es directamente aplicable en los edificios emplazados en Catalu\u00f1a\u00bb, dice <strong>Montse Bassas<\/strong>, vicepresidenta del Colegio de Administradores de Fincas de Lleida y Barcelona, al programa \u00abMa\u00f1anas\u00bb.<\/p>\n<p>Esta \u00faltima sentencia del Supremo reitera otros de anteriores, del 2020 y 2021, y dice que <strong>el pago de las cuotas<\/strong> en la comunidad de propietarios es una <strong>\u00abobligaci\u00f3n peri\u00f3dica\u00bb<\/strong> y que <strong>prescribe en el ninguno de 5 a\u00f1os.<\/strong> \u00abEl problema es que en Catalu\u00f1a tenemos normativa propia con plazos diferentes y con una jurisdicci\u00f3n que no acaba al Tribunal Supremo sino al Tribunal Superior de Justicia, y el Tribunal Superior de Justicia de Catalu\u00f1a (TSJC) no se ha pronunciado sobre este tema\u00bb, explica Bassas.<\/p>\n<p>Los presidentes de las audiencias provinciales de Barcelona emitieron <strong>un criterio unificado<\/strong> en el cual consideraban que son 10 a\u00f1os, pero si hacemos caso de la<strong> normativa catalana de las obligaciones peri\u00f3dicas <\/strong>hablamos <strong>de 3 a\u00f1os.<\/strong> Tambi\u00e9n hay una minor\u00eda que considera que se tiene que<strong> seguir el criterio del Supremo,<\/strong> dice la administradora de fincas.<\/p>\n<h4>\n<strong>Indefensi\u00f3n e inseguridad de los vecinos afectados<\/strong><\/h4>\n<p>Los vecinos son los perjudicados en los casos de morosidad en una comunidad, y esta inconcreci\u00f3n de la ley en Catalu\u00f1a causa \u00abindefensi\u00f3n e inseguridad\u00bb a los propietarios afectados por vecinos morosos, dice a las \u00abMa\u00f1anas\u00bb el abogado de comunidades<strong> Xavier Prats<\/strong>, y propietario afectado.<\/p>\n<p>Hay morosos por varias razones, \u00abgente que <strong>no puede pagar la hipoteca<\/strong> y autom\u00e1ticamente deja de pagar las cuotas comunitarias\u00bb, explica Prats, o tambi\u00e9n por<strong> defunciones. \u00ab<\/strong>Los hijos no aceptan la herencia, o se hacen el remol\u00f3n o no aparece el heredero\u00bb, como <strong>un caso en Lleida donde hace 20 a\u00f1os que intentan encontrar el propietario<\/strong> de un piso despu\u00e9s de la muerte de su propietario. Hay propietarios, explica, que \u00abhan habido hacer muchas\u00a0<strong>derrames\u00a0y anticipos para pagar los gastos<\/strong> de cada mes, como luz, ascensor, seguro&#8230;\u00bb<\/p>\n<p>A pesar de que la mayor\u00eda de los casos se dan en<strong> vecinos que conviven en la misma escalera,<\/strong> dice Balsa seg\u00fan su experiencia, durante la crisis inmobiliaria y la\u00a0covid, muchos pisos cayeron en manos de <strong>bancos y de fondos de inversi\u00f3n<\/strong> y crecieron los impagos. \u00abTuvimos un problema de pisos desocupados y de los que ellos mismos no sab\u00edan qu\u00e9 ten\u00edamos a la cartera\u00bb, dice. Y a\u00f1ade que hay bancos que \u00abtienen la costumbre de aguantar <strong>sin pagar hasta que venden el piso<\/strong> y esto obliga el resto de la comunidad a financiar los gastos\u00bb.<\/p>\n<p>En Catalu\u00f1a <strong>la ley obliga a vender el piso sin cargas<\/strong>, es decir, con todas las deudas pagadas, pero no aclara hasta <strong>cu\u00e1ntos a\u00f1os de deber atrasado puede reclamar la comunidad.<\/strong><\/p>\n<h4>\n<strong>Presentar la reclamaci\u00f3n cuanto antes mejor<\/strong><\/h4>\n<p>Los dos especialistas recomiendan en las comunidades con vecinos morosos que<strong> no esperen a presentar la demanda judicial<\/strong> para evitar \u00abque a pesar de tener derecho a reclamar, (la deuda) est\u00e9 fuera de plazo, est\u00e9 prescrito, y para ver como tienen que reducir la deuda\u00bb, dice Prats.<\/p>\n<p>El criterio de las comunidades tiene que ser de prudencia: no esperar el vencimiento de 3 a\u00f1os, reitera Bassas, y \u00abantes de este vencimiento, poner la reclamaci\u00f3n por no tener que depender de si el juzgado que nos toca es del criterio de 3 a\u00f1os o de 10 a\u00f1os\u00bb.<\/p>\n<h4>\n<strong>Como presentar una reclamaci\u00f3n por morosidad<\/strong><\/h4>\n<p>El primer paso es convocar una reuni\u00f3n o junta de vecinos de la comunidad y que tenga conocimiento el moroso. A la reuni\u00f3n se <strong>aprobar\u00e1 la liquidaci\u00f3n de la deuda pendiente<\/strong> y la decisi\u00f3n de presentar reclamaci\u00f3n <strong>extrajudicial<\/strong>, primero, y<strong> judicial<\/strong>, si hace falta, por mayor\u00eda simple.<\/p>\n<p>\u00abAhora mismo <strong>es obligatoria la mediaci\u00f3n<\/strong> como paso previo a la interposici\u00f3n de la demanda judicial\u00bb, dice Balsa, y, por lo tanto, primero se tiene que hablar con el vecino de manera extrajudicial.<\/p>\n<p>Se comunicar\u00e1 la decisi\u00f3n de la junta al propietario moroso, personalmente, en su domicilio o &#8212; si no es posible &#8212; al cartel de anuncios de la escalera.<\/p>\n<p>Se puede reclamar el impago de <strong>cuotas generales<\/strong>, aportaciones a un <strong>fondo de reserva, o de obras<\/strong> en la comunidad, por un valor m\u00e1ximo de 250.000 euros.<\/p>\n<p>La reclamaci\u00f3n al juzgado tiene que ir acompa\u00f1ada del <strong>acuerdo de junta<\/strong> y de la<strong> comunicaci\u00f3n al deudor.<\/strong><\/p>\n<p>Si la reclamaci\u00f3n es superior a los 2.000 \u20ac y hay que tener abogado y procurador, tambi\u00e9n se pueden a\u00f1adir a la demanda el pago de las costas al moroso.<\/p>\n<p>Si la demanda es aceptada,<strong> el juez reclamar\u00e1 la deuda<\/strong> al propietario denunciado, a pagar en un plazo de 20 d\u00edas, <strong>o se le embargar\u00e1n los bienes<\/strong> por el valor del importe reclamado, m\u00e1s los intereses y gastos judiciales. Una comunicaci\u00f3n que es bastante disuasiva, seg\u00fan Prats.<\/p>\n<p>Con todo, el demandado puede presentar alegaciones y pruebas si cree que <strong>la deuda es inexistente o ya ha hecho el pago.<\/strong><\/p>\n<p>Puedes leer la noticia completa a <a href=\"https:\/\/www.3cat.cat\/3catinfo\/quan-prescriu-el-deute-dun-vei-moros-la-llei-a-catalunya-no-es-clara\/noticia\/3392533\/\">Quan prescriu el deute d&#8217;un ve\u00ed mor\u00f3s: la llei a Catalunya no \u00e9s clara &#8211; 3CatInfo<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-913c7d8 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"913c7d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-125c2f7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"125c2f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Barcelona, 4 de febrero del 2026 Un vecino moroso es la pesadilla de las comunidades de propietarios, porque la deuda recae en la comunidad y puede llegar a ser muy alto. La comunidad de vecinos puede acabar demandando el propietario que no paga, pero hay que tener cuidado con los plazos, porque la deuda prescribe en el ninguno de unos a\u00f1os. Una sentencia reciente del Tribunal Supremo fija en 5 a\u00f1os la prescripci\u00f3n de las deudas en una comunidad de vecinos, pero en Catalu\u00f1a este plazo puede ser diferente. \u00abEn Catalu\u00f1a tenemos normativa y jurisdicci\u00f3n propia, esto quiere decir que la sentencia del Tribunal Supremo no es directamente aplicable en los edificios emplazados en Catalu\u00f1a\u00bb, dice Montse Bassas, vicepresidenta del Colegio de Administradores de Fincas de Lleida y Barcelona, al programa \u00abMa\u00f1anas\u00bb. Esta \u00faltima sentencia del Supremo reitera otros de anteriores, del 2020 y 2021, y dice que el pago de las cuotas en la comunidad de propietarios es una \u00abobligaci\u00f3n peri\u00f3dica\u00bb y que prescribe en el ninguno de 5 a\u00f1os. \u00abEl problema es que en Catalu\u00f1a tenemos normativa propia con plazos diferentes y con una jurisdicci\u00f3n que no acaba al Tribunal Supremo sino al Tribunal Superior de Justicia, y el Tribunal Superior de Justicia de Catalu\u00f1a (TSJC) no se ha pronunciado sobre este tema\u00bb, explica Bassas. Los presidentes de las audiencias provinciales de Barcelona emitieron un criterio unificado en el cual consideraban que son 10 a\u00f1os, pero si hacemos caso de la normativa catalana de las obligaciones peri\u00f3dicas hablamos de 3 a\u00f1os. Tambi\u00e9n hay una minor\u00eda que considera que se tiene que seguir el criterio del Supremo, dice la administradora de fincas. Indefensi\u00f3n e inseguridad de los vecinos afectados Los vecinos son los perjudicados en los casos de morosidad en una comunidad, y esta inconcreci\u00f3n de la ley en Catalu\u00f1a causa \u00abindefensi\u00f3n e inseguridad\u00bb a los propietarios afectados por vecinos morosos, dice a las \u00abMa\u00f1anas\u00bb el abogado de comunidades Xavier Prats, y propietario afectado. Hay morosos por varias razones, \u00abgente que no puede pagar la hipoteca y autom\u00e1ticamente deja de pagar las cuotas comunitarias\u00bb, explica Prats, o tambi\u00e9n por defunciones. \u00abLos hijos no aceptan la herencia, o se hacen el remol\u00f3n o no aparece el heredero\u00bb, como un caso en Lleida donde hace 20 a\u00f1os que intentan encontrar el propietario de un piso despu\u00e9s de la muerte de su propietario. Hay propietarios, explica, que \u00abhan habido hacer muchas\u00a0derrames\u00a0y anticipos para pagar los gastos de cada mes, como luz, ascensor, seguro&#8230;\u00bb A pesar de que la mayor\u00eda de los casos se dan en vecinos que conviven en la misma escalera, dice Balsa seg\u00fan su experiencia, durante la crisis inmobiliaria y la\u00a0covid, muchos pisos cayeron en manos de bancos y de fondos de inversi\u00f3n y crecieron los impagos. \u00abTuvimos un problema de pisos desocupados y de los que ellos mismos no sab\u00edan qu\u00e9 ten\u00edamos a la cartera\u00bb, dice. Y a\u00f1ade que hay bancos que \u00abtienen la costumbre de aguantar sin pagar hasta que venden el piso y esto obliga el resto de la comunidad a financiar los gastos\u00bb. En Catalu\u00f1a la ley obliga a vender el piso sin cargas, es decir, con todas las deudas pagadas, pero no aclara hasta cu\u00e1ntos a\u00f1os de deber atrasado puede reclamar la comunidad. Presentar la reclamaci\u00f3n cuanto antes mejor Los dos especialistas recomiendan en las comunidades con vecinos morosos que no esperen a presentar la demanda judicial para evitar \u00abque a pesar de tener derecho a reclamar, (la deuda) est\u00e9 fuera de plazo, est\u00e9 prescrito, y para ver como tienen que reducir la deuda\u00bb, dice Prats. El criterio de las comunidades tiene que ser de prudencia: no esperar el vencimiento de 3 a\u00f1os, reitera Bassas, y \u00abantes de este vencimiento, poner la reclamaci\u00f3n por no tener que depender de si el juzgado que nos toca es del criterio de 3 a\u00f1os o de 10 a\u00f1os\u00bb. Como presentar una reclamaci\u00f3n por morosidad El primer paso es convocar una reuni\u00f3n o junta de vecinos de la comunidad y que tenga conocimiento el moroso. A la reuni\u00f3n se aprobar\u00e1 la liquidaci\u00f3n de la deuda pendiente y la decisi\u00f3n de presentar reclamaci\u00f3n extrajudicial, primero, y judicial, si hace falta, por mayor\u00eda simple. \u00abAhora mismo es obligatoria la mediaci\u00f3n como paso previo a la interposici\u00f3n de la demanda judicial\u00bb, dice Balsa, y, por lo tanto, primero se tiene que hablar con el vecino de manera extrajudicial. Se comunicar\u00e1 la decisi\u00f3n de la junta al propietario moroso, personalmente, en su domicilio o &#8212; si no es posible &#8212; al cartel de anuncios de la escalera. Se puede reclamar el impago de cuotas generales, aportaciones a un fondo de reserva, o de obras en la comunidad, por un valor m\u00e1ximo de 250.000 euros. La reclamaci\u00f3n al juzgado tiene que ir acompa\u00f1ada del acuerdo de junta y de la comunicaci\u00f3n al deudor. Si la reclamaci\u00f3n es superior a los 2.000 \u20ac y hay que tener abogado y procurador, tambi\u00e9n se pueden a\u00f1adir a la demanda el pago de las costas al moroso. Si la demanda es aceptada, el juez reclamar\u00e1 la deuda al propietario denunciado, a pagar en un plazo de 20 d\u00edas, o se le embargar\u00e1n los bienes por el valor del importe reclamado, m\u00e1s los intereses y gastos judiciales. Una comunicaci\u00f3n que es bastante disuasiva, seg\u00fan Prats. Con todo, el demandado puede presentar alegaciones y pruebas si cree que la deuda es inexistente o ya ha hecho el pago. Puedes leer la noticia completa a Quan prescriu el deute d&#8217;un ve\u00ed mor\u00f3s: la llei a Catalunya no \u00e9s clara &#8211; 3CatInfo.<\/p>\n","protected":false},"author":1,"featured_media":96918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[1277],"class_list":["post-153874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-prensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.<\/title>\n<meta name=\"description\" content=\"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\" \/>\n<meta property=\"og:description\" content=\"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi Administradors de Finques Barcelona Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T11:34:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T11:52:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/TV-3cat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adminwpcafbl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CAFbcn_lleida\" \/>\n<meta name=\"twitter:site\" content=\"@CAFbcn_lleida\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminwpcafbl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/\"},\"author\":{\"name\":\"adminwpcafbl\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/person\\\/bfdd3486c3f782e0fd324b2d5a98ef47\"},\"headline\":\"Cuando prescribe la deuda de un vecino moroso: la ley en Catalu\u00f1a no es clara\",\"datePublished\":\"2026-02-04T11:34:44+00:00\",\"dateModified\":\"2026-02-23T11:52:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/\"},\"wordCount\":990,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/TV-3cat.png\",\"keywords\":[\"Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/\",\"name\":\"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/TV-3cat.png\",\"datePublished\":\"2026-02-04T11:34:44+00:00\",\"dateModified\":\"2026-02-23T11:52:14+00:00\",\"description\":\"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/TV-3cat.png\",\"contentUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/TV-3cat.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuando prescribe la deuda de un vecino moroso: la ley en Catalu\u00f1a no es clara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/\",\"name\":\"Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"description\":\"Web oficial del Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#organization\"},\"alternateName\":\"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"alternateName\":\"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo_cafbl.svg\",\"contentUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo_cafbl.svg\",\"width\":471,\"height\":116,\"caption\":\"Col\u00b7legi Administradors de Finques Barcelona Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/CAFbcn_lleida\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/administradors-finques-cafbl\",\"https:\\\/\\\/www.instagram.com\\\/administradors_finques_cafbl\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/person\\\/bfdd3486c3f782e0fd324b2d5a98ef47\",\"name\":\"adminwpcafbl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g\",\"caption\":\"adminwpcafbl\"},\"sameAs\":[\"https:\\\/\\\/cafbl.cat\"],\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/author\\\/adminwpcafbl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","description":"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/","og_locale":"es_ES","og_type":"article","og_title":"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","og_description":"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","og_url":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/","og_site_name":"Col\u00b7legi Administradors de Finques Barcelona Lleida","article_published_time":"2026-02-04T11:34:44+00:00","article_modified_time":"2026-02-23T11:52:14+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/TV-3cat.png","type":"image\/png"}],"author":"adminwpcafbl","twitter_card":"summary_large_image","twitter_creator":"@CAFbcn_lleida","twitter_site":"@CAFbcn_lleida","twitter_misc":{"Escrito por":"adminwpcafbl","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#article","isPartOf":{"@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/"},"author":{"name":"adminwpcafbl","@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/person\/bfdd3486c3f782e0fd324b2d5a98ef47"},"headline":"Cuando prescribe la deuda de un vecino moroso: la ley en Catalu\u00f1a no es clara","datePublished":"2026-02-04T11:34:44+00:00","dateModified":"2026-02-23T11:52:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/"},"wordCount":990,"publisher":{"@id":"https:\/\/www.cafbl.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/TV-3cat.png","keywords":["Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/","url":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/","name":"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","isPartOf":{"@id":"https:\/\/www.cafbl.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#primaryimage"},"image":{"@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/TV-3cat.png","datePublished":"2026-02-04T11:34:44+00:00","dateModified":"2026-02-23T11:52:14+00:00","description":"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","breadcrumb":{"@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#primaryimage","url":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/TV-3cat.png","contentUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/TV-3cat.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.cafbl.cat\/es\/cuando-prescribe-la-deuda-de-un-vecino-moroso-la-ley-en-cataluna-no-es-clara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cafbl.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Cuando prescribe la deuda de un vecino moroso: la ley en Catalu\u00f1a no es clara"}]},{"@type":"WebSite","@id":"https:\/\/www.cafbl.cat\/es\/#website","url":"https:\/\/www.cafbl.cat\/es\/","name":"Col\u00b7legi Administradors de Finques Barcelona Lleida","description":"Web oficial del Col\u00b7legi Administradors de Finques Barcelona Lleida","publisher":{"@id":"https:\/\/www.cafbl.cat\/es\/#organization"},"alternateName":"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cafbl.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cafbl.cat\/es\/#organization","name":"Col\u00b7legi Administradors de Finques Barcelona Lleida","alternateName":"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida","url":"https:\/\/www.cafbl.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2024\/07\/logo_cafbl.svg","contentUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2024\/07\/logo_cafbl.svg","width":471,"height":116,"caption":"Col\u00b7legi Administradors de Finques Barcelona Lleida"},"image":{"@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/CAFbcn_lleida","https:\/\/www.linkedin.com\/company\/administradors-finques-cafbl","https:\/\/www.instagram.com\/administradors_finques_cafbl\/"]},{"@type":"Person","@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/person\/bfdd3486c3f782e0fd324b2d5a98ef47","name":"adminwpcafbl","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g","caption":"adminwpcafbl"},"sameAs":["https:\/\/cafbl.cat"],"url":"https:\/\/www.cafbl.cat\/es\/author\/adminwpcafbl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/posts\/153874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/comments?post=153874"}],"version-history":[{"count":0,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/posts\/153874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/media\/96918"}],"wp:attachment":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/media?parent=153874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/categories?post=153874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/tags?post=153874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}