{"id":153959,"date":"2026-01-05T13:57:23","date_gmt":"2026-01-05T12:57:23","guid":{"rendered":"https:\/\/www.cafbl.cat\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/"},"modified":"2026-02-25T14:18:21","modified_gmt":"2026-02-25T13:18:21","slug":"mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc","status":"publish","type":"post","link":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/","title":{"rendered":"\u00bfMejor comprar o alquilar, en 2026?: tres claves del mercado inmobiliario en Barcelona ante los altos precios y el escaso estoc"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"153959\" class=\"elementor elementor-153959 elementor-153942\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed910 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ed910\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66d61f6e elementor-widget elementor-widget-text-editor\" data-id=\"66d61f6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Barcelona, 5 de enero del 2026<\/p>\n<p>Tras un a\u00f1o marcado por el\u00a0<strong>aumento de los precios de la vivienda,<\/strong>\u00a0tanto de compra como de alquiler en\u00a0<strong>Barcelona<\/strong>, y por la creciente dificultad de\u00a0<strong>acceso\u00a0<\/strong>para muchos colectivos, las previsiones para 2026 en el seno del sector son poco alentadoras para los barceloneses. La fuerte\u00a0<strong>demanda\u00a0<\/strong>en la capital catalana mantendr\u00e1 lo<strong>s precios al alza<\/strong>\u00a0en ambos frentes, con la sospecha de que muchas viviendas de\u00a0<a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20251217\/barcelona-aplicara-inmediato-nueva-regulacion-alquiler-temporada-124878539\" data-mrf-recirculation=\"news-enlace-texto\" data-mrf-link=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20251217\/barcelona-aplicara-inmediato-nueva-regulacion-alquiler-temporada-124878539\">alquiler de temporada saldr\u00e1n del mercado tras la nueva regulaci\u00f3n<\/a>\u00a0y optar\u00e1n por la venta, lo que aumentar\u00e1 la\u00a0<strong>pugna\u00a0<\/strong>por el arrendamiento convencional, seg\u00fan pronostican asociaciones de propietarios, de agentes de la propiedad, de administradores de fincas y portales inmobiliarios especializados a este diario. Estas ser\u00e1n algunas de las claves del pr\u00f3ximo a\u00f1o:<\/p>\n<h3 class=\"ft-helper-spacer-t-xs ft-helper-fontSize-heading-XS\">Evoluci\u00f3n de los precios a\u00fan en aumento<\/h3>\n<p><\/p>\n<p class=\"ft-text\">Hay unanimidad entre los consultados sobre el empuje de los precios, incluso en un contexto de limitaci\u00f3n de rentas como el que impuso la Generalitat, que en el\u00a0<a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20251106\/alquileres-suben-ocho-distritos-47-barrios-barcelona-segundo-trimestre-2025-123413471\" data-mrf-recirculation=\"news-enlace-texto\" data-mrf-link=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20251106\/alquileres-suben-ocho-distritos-47-barrios-barcelona-segundo-trimestre-2025-123413471\">\u00faltimo registro oficial del Incasol ya mostraban un repunte en la mayor\u00eda de zonas de Barcelona<\/a>. Se explica por las actualizaciones legales anuales, y por el evidente incumplimiento de la normativa en muchos casos, ante un operativo sancionador que no act\u00faa de oficio en cada uno de los contratos. Seg\u00fan mantiene la\u00a0<strong>Cambra de la Propietat Urbana de Barcelona<\/strong>, \u00ablos precios seguir\u00e1n al alza aunque de forma m\u00e1s moderada que en 2025\u00bb. En compraventa prev\u00e9n subidas \u00abcontenidas\u00bb por la demanda muy activa en \u00abzonas consolidadas\u00bb, aunque los tipos de inter\u00e9s podr\u00edan encarecerse. Pero la demanda seguir\u00e1 siendo \u00absolvente\u00bb, lo que mantendr\u00e1 \u00abvivo el ritmo de ventas\u00bb, detalla su gerente y analista,\u00a0<strong>\u00d3scar Gorgues.<\/strong>\u00a0En cambio, creen que en alquiler el estoc seguir\u00e1 reduci\u00e9ndose o estancado, propiciando \u00abuna fuerte\u00a0<strong>competencia\u00a0<\/strong>entre inquilinos\u00bb.<\/p>\n<p>Tambi\u00e9n la asociaci\u00f3n de propietarios de viviendas en alquiler\u00a0<strong>ASVAL\u00a0<\/strong>alude a un \u00ab<strong>desequilibrio\u00a0<\/strong>estructural entre una demanda que crece y una oferta que no consigue acompa\u00f1ar\u00bb. Vaticinan alza de precios y estoc de alquiler \u00abr\u00edgido y con menor rotaci\u00f3n\u00bb, con \u00abm\u00e1s propietarios que salen o no entran\u00bb por el control de precios, que se ha acompa\u00f1ado de un \u00abdeterioro de la oferta, inmuebles m\u00e1s peque\u00f1os y de peor calidad\u00bb.<\/p>\n<p class=\"ft-text\">Desde\u00a0<strong>API BCN,<\/strong>\u00a0pronostican la \u00abcontinuidad de precios al alza\u00bb sobre todo en zonas bien conectadas, dada la poca oferta. Alertan de la salida masiva de producto de alquiler tradicional, \u00abno con l\u00f3gica especulativa sino en busca de un marco jur\u00eddico m\u00e1s estable\u00bb, como pod\u00edan ser hasta ahora los contratos temporales, para evitar posibles\u00a0<strong>sanciones\u00a0<\/strong>y otros riesgos. El colectivo de agentes de la propiedad inmobiliaria cree que el arrendamiento de temporada obedece a una demanda \u00abreal\u00bb pero no da respuesta la necesidad de vivienda habitual. Pronostican que las soluciones temporales o compartidas ser\u00e1n la \u00fanica v\u00eda para quienes no pueden acceder a un contrato largo, cada vez m\u00e1s competido. Quienes se lo puedan permitir dar\u00e1n el salto a la compra.<\/p>\n<p><\/p>\n<p class=\"ft-text\">Lorenzo Vi\u00f1as, presidente del<strong>\u00a0Col\u00b7legi d&#8217;Administradors de Finques de Barcelona-Lleida<\/strong>\u00a0agrega \u00absin riesgo de error\u00bb que en los pr\u00f3ximos 24 meses se mantendr\u00e1 el desencuentro entre oferta y demanda, \u00abforzando\u00bb la subida de precios, lo que derivar\u00e1 cada vez m\u00e1s en un \u00abpa\u00eds de propietarios endeudados\u00bb. Opina que el \u00abintervencionismo\u00bb del Govern acarrear\u00e1 \u00abla imposibilidad de acceder a la vivienda de alquiler\u00bb por parte incluso de familias con capacidad econ\u00f3mica suficiente, ante el d\u00e9ficit de pisos ofertados. Si no hay cambios normativos, cree que los j\u00f3venes lo tendr\u00e1n dif\u00edcil en 2026.<\/p>\n<p><\/p>\n<p class=\"ft-text\">Los analistas de\u00a0<strong>Idealista\u00a0<\/strong>a\u00f1aden que \u00aben Barcelona, por su peculiar situaci\u00f3n, los precios de compraventa crecer\u00e1n a un solo d\u00edgito &#8211;en 2025 subieron un 9,4% interanual, en el \u00faltimo trimestre&#8211;, al haber paliado la reducci\u00f3n de oferta con las viviendas provenientes del mercado del alquiler\u00bb, por efecto de la limitaci\u00f3n de las rentas.<\/p>\n<p><\/p>\n<p class=\"ft-text\">Desde las patronales catalanas de propietarios ahondan en las nubes negras. El presidente de la\u00a0<strong>Associaci\u00f3 de Propietaris de Catalunya,\u00a0<\/strong>Sergi Llagostera<strong>,<\/strong>\u00a0cree que el pr\u00f3ximo a\u00f1o la oferta en alquiler seguir\u00e1 a la baja por el miedo de los propietarios, a la par que crecen los aspirantes a inquilinos, para perjuicio de \u00abj\u00f3venes, familias y gente con poca solvencia econ\u00f3mica\u00bb. La entidad de reciente creaci\u00f3n S<strong>om Habitatge<\/strong>\u00a0apunta que los propietarios seguir\u00e1n saliendo del mercado de alquiler, espoleados por la imposibilidad de desahuciar a inquilinos \u00abdeclarados vulnerables\u00bb que han llevado a los \u00abparticulares a asumir una carga social que deber\u00eda corresponder al Estado\u00bb, por la limitaci\u00f3n de rentas con \u00edndices de referencia \u00abque no reflejan los costes reales del inmueble ni permiten un retorno de la inversi\u00f3n\u00bb, y un \u00abr\u00e9gimen sancionador desproporcionado\u00bb.<\/p>\n<h3 class=\"ft-helper-spacer-t-xs ft-helper-fontSize-heading-XS\">\u00bfMejor a\u00f1o para comprar o para alquilar?<\/h3>\n<p><\/p>\n<p class=\"ft-text\">La gran pregunta de todo el que busca piso es qu\u00e9 opci\u00f3n es la adecuada con los precios por las nubes en la mayor\u00eda de zonas de Barcelona.\u00a0<strong>ASVAL\u00a0<\/strong>subraya que la movilidad laboral y generaci\u00f3n de nuevos hogares lo pondr\u00e1 m\u00e1s dif\u00edcil para arrendar, ya que la oferta que sale del mercado \u00abno se repone\u00bb y urge a reactivar \u00abde forma clara la producci\u00f3n de vivienda nueva para alquilar\u00bb. En cambio, la\u00a0<strong>Cambra de la Propietat\u00a0<\/strong>no duda que \u00aben t\u00e9rminos relativos, en 2026 ser\u00e1 mejor comprar porque el alquiler estar\u00e1 muy competido\u00bb, lo que ya est\u00e1 impulsando \u00abmovimientos hacia la periferia\u00bb de la capital catalana para la compra. Esa perspectiva \u00abofrece m\u00e1s estabilidad, previsibilidad de costes y protecci\u00f3n\u00bb y las actuales hipotecas fijas \u00abaportan certidumbre al comprador\u00bb. Sin olvidar, precisa Gorgues, que \u00abel alquiler es un gasto, mientras la cuota hipotecaria tiene un componente de\u00a0<strong>inversi\u00f3n\u00a0<\/strong>patrimonial\u00bb, sobre todo en Barcelona.<\/p>\n<p><\/p>\n<p class=\"ft-text\">Los\u00a0<strong>API\u00a0<\/strong>de la ciudad creen que todo depende de la estabilidad laboral, ahorro y capacidad de endeudamiento de cada uno, pero creen que \u00abesperar a que todo baje no es hoy una estrategia realista para la mayor\u00eda\u00bb. La competencia ser\u00e1 el principal h\u00e1ndicap para alquilar, para quienes busquen flexibilidad. Pero quien tenga un \u00abhorizonte de permanencia\u00bb puede \u00abvalorar la compra con prudencia y buen asesoramiento profesional\u00bb, tercian.<\/p>\n<p><\/p>\n<p class=\"ft-text\">Por parte de los\u00a0<strong>administradores\u00a0<\/strong>de fincas, \u00abya no es una cuesti\u00f3n de libre elecci\u00f3n\u00bb, ya que \u00abquien pueda pagar una hipoteca deber\u00e1 acudir a la compra como \u00fanica opci\u00f3n habitacional y quien no, alejarse de la ciudad\u00bb.<\/p>\n<p><\/p>\n<p class=\"ft-text\"><strong>Fotocasa\u00a0<\/strong>alerta de la tendencia a alcanzar precios m\u00e1ximos hist\u00f3ricos en la vivienda en venta, mientras que las subidas en el alquiler se moderan, aunque resultar\u00e1n inaccesibles a las rentas m\u00e1s bajas, que optar\u00e1n por buscar hogar en otros municipios m\u00e1s asequibles.<\/p>\n<p><\/p>\n<p class=\"ft-text\"><strong>Som Habitatge<\/strong>\u00a0mantiene que \u00abser\u00e1 un a\u00f1o muy desfavorable para el mercado inmobiliario, tanto en alquiler como compraventa. Con un mercado tan tenso que agravar\u00e1 \u00abla exclusi\u00f3n de colectivos vulnerables y j\u00f3venes\u00bb y se \u00abintensificar\u00e1\u00bb por la \u00abeconom\u00eda sumergida, la falta de est\u00edmulos para la rehabilitaci\u00f3n y obra nueva, o para la conversi\u00f3n de locales en vivienda\u00bb. Por ello pronostican un \u00abdeterioro generacional y social significativo\u00bb.<\/p>\n<p><\/p>\n<p class=\"ft-text\">En opini\u00f3n de la\u00a0<strong>Associaci\u00f3 de Propietaris de Catalunya<\/strong>, la situaci\u00f3n \u00abser\u00e1 peor\u00bb, dados el \u00abcolapso del mercado de alquiler\u00bb llevar\u00e1 a una mayor demanda de compra y en consecuencia un \u00abencarecimiento de su precio\u00bb.<\/p>\n<h3 class=\"ft-helper-spacer-t-xs ft-helper-fontSize-heading-XS\">Propuestas para mejorar el acceso a la vivienda<\/h3>\n<p><\/p>\n<p class=\"ft-text\">Ampliar la oferta con incentivos a la construcci\u00f3n y a la fiscalidad del alquiler son sugerencias mencionadas como urgentes. Para el Col\u00b7legi d&#8217;Administradors de Finques de Barcelona-Lleida, se necesita \u00abcolaboraci\u00f3n p\u00fablico-privada\u00bb, en lugar de \u00abdenigrar la figura del propietario\u00bb y multarlo, as\u00ed como promocionando m\u00e1s vivienda asequible por parte de las administraciones, hasta equiparar la balanza de oferta y demanda.<\/p>\n<p><\/p>\n<p class=\"ft-text\">Som Habitatge apremia a impulsar\u00a0<strong>rehabilitaciones\u00a0<\/strong>de edificios existentes, adem\u00e1s de \u00abla conversi\u00f3n de oficinas y locales en vivienda, permitiendo cambios de uso\u00bb; incentivar la construcci\u00f3n de obra nueva destinada sobre todo a alquiler social; optimizar el uso del suelo mediante planes urban\u00edsticos flexibles que faciliten la densificaci\u00f3n responsable\u00bb; facilitar el acceso a compra y alquiler con programas de ayuda directa a j\u00f3venes colectivos vulnerables; promover modelos cooperativos o compartidos; incentivar la compra con\u00a0<strong>medidas fiscales\u00a0<\/strong>reduciendo el impuesto de transmisiones patrimoniales al 1% en primera vivienda sin l\u00edmite de edad, entre otras; prever el desalojo inmediato de okupas en 24 horas y agilizar los desahucios a tres meses; as\u00ed como eliminar los \u00edndices de referencia de alquiler, que \u00abfomentan el fraude\u00bb.<\/p>\n<p><\/p>\n<p class=\"ft-text\">ASVAL receta \u00ab<strong>seguridad\u00a0<\/strong>jur\u00eddica y estabilidad regulatoria\u00bb para promover la puesta de viviendas en el mercado, as\u00ed como su rehabilitaci\u00f3n. Mientras que la Associaci\u00f3 de Propietaris de Catalunya, a\u00f1ade que se incrementen a 10 las propiedades que definen al gran tenedor (en lugar de 5 &#8211;en zonas tensionadas&#8211; en Catalunya) como en el resto del Estado, para evitar que muchos peque\u00f1os propietarios (el perfil mayoritario en Catalunya) dejen de alquilar.<\/p>\n<p><\/p>\n<p class=\"ft-text\">En la Cambra se\u00f1alan que sin aumentar la oferta, cualquier medida solo centrada en la demanda tiene un \u00abefecto limitado\u00bb. Consideran \u00ableg\u00edtimo preguntarse hasta qu\u00e9 punto la ciudad puede absorber crecimientos demogr\u00e1ficos tan intensos en plazos cortos sin tensionar a\u00fan m\u00e1s el mercado residencial, las infraestructuras y los servicios p\u00fablicos\u00bb. Cuestionan tambi\u00e9n la \u00absostenibilidad del modelo econ\u00f3mico de Barcelona, muy intensivo en mano de obra\u00bb pero con \u00absalarios bajos\u00bb, de modo que una parte creciente de poblaci\u00f3n no puede asumir los costes de la vivienda. Adem\u00e1s de seguridad jur\u00eddica para incentivar el mercado, aluden tambi\u00e9n a propiciar los cambios de uso.<\/p>\n<p>Los API alertan de que el problema es estructural y no tiene soluciones r\u00e1pidas, enfocando el objetivo en generar m\u00e1s vivienda asequible. En ese sentido, impulsaron el reciente\u00a0<a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20251030\/propietarios-venden-evitar-problemas-api-lanzan-pacto-vivienda-catalunya-123178336\" data-mrf-recirculation=\"news-enlace-texto\" data-mrf-link=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20251030\/propietarios-venden-evitar-problemas-api-lanzan-pacto-vivienda-catalunya-123178336\">Pacte Transversal per l&#8217;Habitatge,<\/a>\u00a0donde recogen propuestas que van de la activaci\u00f3n de suelo a la estabilidad normativa.<\/p>\n<p>Puedes leer la noticia completa a: \u00a0<a href=\"https:\/\/www.elperiodico.com\/es\/barcelona\/20260104\/claves-mercado-inmobiliario-2026-barcelona-alquiler-venta-precios-125066391\">\u00bfMejor comprar o alquilar, en 2026?: tres claves del mercado inmobiliario en Barcelona ante los altos precios y el escaso estoc<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-913c7d8 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"913c7d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-125c2f7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"125c2f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Barcelona, 5 de enero del 2026 Tras un a\u00f1o marcado por el\u00a0aumento de los precios de la vivienda,\u00a0tanto de compra como de alquiler en\u00a0Barcelona, y por la creciente dificultad de\u00a0acceso\u00a0para muchos colectivos, las previsiones para 2026 en el seno del sector son poco alentadoras para los barceloneses. La fuerte\u00a0demanda\u00a0en la capital catalana mantendr\u00e1 los precios al alza\u00a0en ambos frentes, con la sospecha de que muchas viviendas de\u00a0alquiler de temporada saldr\u00e1n del mercado tras la nueva regulaci\u00f3n\u00a0y optar\u00e1n por la venta, lo que aumentar\u00e1 la\u00a0pugna\u00a0por el arrendamiento convencional, seg\u00fan pronostican asociaciones de propietarios, de agentes de la propiedad, de administradores de fincas y portales inmobiliarios especializados a este diario. Estas ser\u00e1n algunas de las claves del pr\u00f3ximo a\u00f1o: Evoluci\u00f3n de los precios a\u00fan en aumento Hay unanimidad entre los consultados sobre el empuje de los precios, incluso en un contexto de limitaci\u00f3n de rentas como el que impuso la Generalitat, que en el\u00a0\u00faltimo registro oficial del Incasol ya mostraban un repunte en la mayor\u00eda de zonas de Barcelona. Se explica por las actualizaciones legales anuales, y por el evidente incumplimiento de la normativa en muchos casos, ante un operativo sancionador que no act\u00faa de oficio en cada uno de los contratos. Seg\u00fan mantiene la\u00a0Cambra de la Propietat Urbana de Barcelona, \u00ablos precios seguir\u00e1n al alza aunque de forma m\u00e1s moderada que en 2025\u00bb. En compraventa prev\u00e9n subidas \u00abcontenidas\u00bb por la demanda muy activa en \u00abzonas consolidadas\u00bb, aunque los tipos de inter\u00e9s podr\u00edan encarecerse. Pero la demanda seguir\u00e1 siendo \u00absolvente\u00bb, lo que mantendr\u00e1 \u00abvivo el ritmo de ventas\u00bb, detalla su gerente y analista,\u00a0\u00d3scar Gorgues.\u00a0En cambio, creen que en alquiler el estoc seguir\u00e1 reduci\u00e9ndose o estancado, propiciando \u00abuna fuerte\u00a0competencia\u00a0entre inquilinos\u00bb. Tambi\u00e9n la asociaci\u00f3n de propietarios de viviendas en alquiler\u00a0ASVAL\u00a0alude a un \u00abdesequilibrio\u00a0estructural entre una demanda que crece y una oferta que no consigue acompa\u00f1ar\u00bb. Vaticinan alza de precios y estoc de alquiler \u00abr\u00edgido y con menor rotaci\u00f3n\u00bb, con \u00abm\u00e1s propietarios que salen o no entran\u00bb por el control de precios, que se ha acompa\u00f1ado de un \u00abdeterioro de la oferta, inmuebles m\u00e1s peque\u00f1os y de peor calidad\u00bb. Desde\u00a0API BCN,\u00a0pronostican la \u00abcontinuidad de precios al alza\u00bb sobre todo en zonas bien conectadas, dada la poca oferta. Alertan de la salida masiva de producto de alquiler tradicional, \u00abno con l\u00f3gica especulativa sino en busca de un marco jur\u00eddico m\u00e1s estable\u00bb, como pod\u00edan ser hasta ahora los contratos temporales, para evitar posibles\u00a0sanciones\u00a0y otros riesgos. El colectivo de agentes de la propiedad inmobiliaria cree que el arrendamiento de temporada obedece a una demanda \u00abreal\u00bb pero no da respuesta la necesidad de vivienda habitual. Pronostican que las soluciones temporales o compartidas ser\u00e1n la \u00fanica v\u00eda para quienes no pueden acceder a un contrato largo, cada vez m\u00e1s competido. Quienes se lo puedan permitir dar\u00e1n el salto a la compra. Lorenzo Vi\u00f1as, presidente del\u00a0Col\u00b7legi d&#8217;Administradors de Finques de Barcelona-Lleida\u00a0agrega \u00absin riesgo de error\u00bb que en los pr\u00f3ximos 24 meses se mantendr\u00e1 el desencuentro entre oferta y demanda, \u00abforzando\u00bb la subida de precios, lo que derivar\u00e1 cada vez m\u00e1s en un \u00abpa\u00eds de propietarios endeudados\u00bb. Opina que el \u00abintervencionismo\u00bb del Govern acarrear\u00e1 \u00abla imposibilidad de acceder a la vivienda de alquiler\u00bb por parte incluso de familias con capacidad econ\u00f3mica suficiente, ante el d\u00e9ficit de pisos ofertados. Si no hay cambios normativos, cree que los j\u00f3venes lo tendr\u00e1n dif\u00edcil en 2026. Los analistas de\u00a0Idealista\u00a0a\u00f1aden que \u00aben Barcelona, por su peculiar situaci\u00f3n, los precios de compraventa crecer\u00e1n a un solo d\u00edgito &#8211;en 2025 subieron un 9,4% interanual, en el \u00faltimo trimestre&#8211;, al haber paliado la reducci\u00f3n de oferta con las viviendas provenientes del mercado del alquiler\u00bb, por efecto de la limitaci\u00f3n de las rentas. Desde las patronales catalanas de propietarios ahondan en las nubes negras. El presidente de la\u00a0Associaci\u00f3 de Propietaris de Catalunya,\u00a0Sergi Llagostera,\u00a0cree que el pr\u00f3ximo a\u00f1o la oferta en alquiler seguir\u00e1 a la baja por el miedo de los propietarios, a la par que crecen los aspirantes a inquilinos, para perjuicio de \u00abj\u00f3venes, familias y gente con poca solvencia econ\u00f3mica\u00bb. La entidad de reciente creaci\u00f3n Som Habitatge\u00a0apunta que los propietarios seguir\u00e1n saliendo del mercado de alquiler, espoleados por la imposibilidad de desahuciar a inquilinos \u00abdeclarados vulnerables\u00bb que han llevado a los \u00abparticulares a asumir una carga social que deber\u00eda corresponder al Estado\u00bb, por la limitaci\u00f3n de rentas con \u00edndices de referencia \u00abque no reflejan los costes reales del inmueble ni permiten un retorno de la inversi\u00f3n\u00bb, y un \u00abr\u00e9gimen sancionador desproporcionado\u00bb. \u00bfMejor a\u00f1o para comprar o para alquilar? La gran pregunta de todo el que busca piso es qu\u00e9 opci\u00f3n es la adecuada con los precios por las nubes en la mayor\u00eda de zonas de Barcelona.\u00a0ASVAL\u00a0subraya que la movilidad laboral y generaci\u00f3n de nuevos hogares lo pondr\u00e1 m\u00e1s dif\u00edcil para arrendar, ya que la oferta que sale del mercado \u00abno se repone\u00bb y urge a reactivar \u00abde forma clara la producci\u00f3n de vivienda nueva para alquilar\u00bb. En cambio, la\u00a0Cambra de la Propietat\u00a0no duda que \u00aben t\u00e9rminos relativos, en 2026 ser\u00e1 mejor comprar porque el alquiler estar\u00e1 muy competido\u00bb, lo que ya est\u00e1 impulsando \u00abmovimientos hacia la periferia\u00bb de la capital catalana para la compra. Esa perspectiva \u00abofrece m\u00e1s estabilidad, previsibilidad de costes y protecci\u00f3n\u00bb y las actuales hipotecas fijas \u00abaportan certidumbre al comprador\u00bb. Sin olvidar, precisa Gorgues, que \u00abel alquiler es un gasto, mientras la cuota hipotecaria tiene un componente de\u00a0inversi\u00f3n\u00a0patrimonial\u00bb, sobre todo en Barcelona. Los\u00a0API\u00a0de la ciudad creen que todo depende de la estabilidad laboral, ahorro y capacidad de endeudamiento de cada uno, pero creen que \u00abesperar a que todo baje no es hoy una estrategia realista para la mayor\u00eda\u00bb. La competencia ser\u00e1 el principal h\u00e1ndicap para alquilar, para quienes busquen flexibilidad. Pero quien tenga un \u00abhorizonte de permanencia\u00bb puede \u00abvalorar la compra con prudencia y buen asesoramiento profesional\u00bb, tercian. Por parte de los\u00a0administradores\u00a0de fincas, \u00abya no es una cuesti\u00f3n de libre elecci\u00f3n\u00bb, ya que \u00abquien pueda pagar una hipoteca deber\u00e1 acudir a la compra como \u00fanica opci\u00f3n habitacional y quien no, alejarse de la ciudad\u00bb. Fotocasa\u00a0alerta de la tendencia a alcanzar precios m\u00e1ximos hist\u00f3ricos en la vivienda<\/p>\n","protected":false},"author":1,"featured_media":96905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[1277],"class_list":["post-153959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-prensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.<\/title>\n<meta name=\"description\" content=\"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\" \/>\n<meta property=\"og:description\" content=\"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi Administradors de Finques Barcelona Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T12:57:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T13:18:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/Premsa-El-Periodico.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adminwpcafbl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CAFbcn_lleida\" \/>\n<meta name=\"twitter:site\" content=\"@CAFbcn_lleida\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminwpcafbl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/\"},\"author\":{\"name\":\"adminwpcafbl\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/person\\\/bfdd3486c3f782e0fd324b2d5a98ef47\"},\"headline\":\"\u00bfMejor comprar o alquilar, en 2026?: tres claves del mercado inmobiliario en Barcelona ante los altos precios y el escaso estoc\",\"datePublished\":\"2026-01-05T12:57:23+00:00\",\"dateModified\":\"2026-02-25T13:18:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/\"},\"wordCount\":1741,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Premsa-El-Periodico.png\",\"keywords\":[\"Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/\",\"name\":\"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Premsa-El-Periodico.png\",\"datePublished\":\"2026-01-05T12:57:23+00:00\",\"dateModified\":\"2026-02-25T13:18:21+00:00\",\"description\":\"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Premsa-El-Periodico.png\",\"contentUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Premsa-El-Periodico.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfMejor comprar o alquilar, en 2026?: tres claves del mercado inmobiliario en Barcelona ante los altos precios y el escaso estoc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/\",\"name\":\"Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"description\":\"Web oficial del Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#organization\"},\"alternateName\":\"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"alternateName\":\"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo_cafbl.svg\",\"contentUrl\":\"https:\\\/\\\/www.cafbl.cat\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo_cafbl.svg\",\"width\":471,\"height\":116,\"caption\":\"Col\u00b7legi Administradors de Finques Barcelona Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/CAFbcn_lleida\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/administradors-finques-cafbl\",\"https:\\\/\\\/www.instagram.com\\\/administradors_finques_cafbl\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/#\\\/schema\\\/person\\\/bfdd3486c3f782e0fd324b2d5a98ef47\",\"name\":\"adminwpcafbl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g\",\"caption\":\"adminwpcafbl\"},\"sameAs\":[\"https:\\\/\\\/cafbl.cat\"],\"url\":\"https:\\\/\\\/www.cafbl.cat\\\/es\\\/author\\\/adminwpcafbl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","description":"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/","og_locale":"es_ES","og_type":"article","og_title":"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","og_description":"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","og_url":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/","og_site_name":"Col\u00b7legi Administradors de Finques Barcelona Lleida","article_published_time":"2026-01-05T12:57:23+00:00","article_modified_time":"2026-02-25T13:18:21+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/Premsa-El-Periodico.png","type":"image\/png"}],"author":"adminwpcafbl","twitter_card":"summary_large_image","twitter_creator":"@CAFbcn_lleida","twitter_site":"@CAFbcn_lleida","twitter_misc":{"Escrito por":"adminwpcafbl","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#article","isPartOf":{"@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/"},"author":{"name":"adminwpcafbl","@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/person\/bfdd3486c3f782e0fd324b2d5a98ef47"},"headline":"\u00bfMejor comprar o alquilar, en 2026?: tres claves del mercado inmobiliario en Barcelona ante los altos precios y el escaso estoc","datePublished":"2026-01-05T12:57:23+00:00","dateModified":"2026-02-25T13:18:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/"},"wordCount":1741,"publisher":{"@id":"https:\/\/www.cafbl.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/Premsa-El-Periodico.png","keywords":["Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/","url":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/","name":"Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","isPartOf":{"@id":"https:\/\/www.cafbl.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#primaryimage"},"image":{"@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/Premsa-El-Periodico.png","datePublished":"2026-01-05T12:57:23+00:00","dateModified":"2026-02-25T13:18:21+00:00","description":"Canal oficial de noticias del CAFBL: Decenas de comunidades de Viladecans, estafadas: la administradora ha vaciado sus cuentas y ha desaparecido.","breadcrumb":{"@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#primaryimage","url":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/Premsa-El-Periodico.png","contentUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2025\/04\/Premsa-El-Periodico.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.cafbl.cat\/es\/mejor-comprar-o-alquilar-en-2026-tres-claves-del-mercado-inmobiliario-en-barcelona-ante-los-altos-precios-y-el-escaso-estoc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cafbl.cat\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfMejor comprar o alquilar, en 2026?: tres claves del mercado inmobiliario en Barcelona ante los altos precios y el escaso estoc"}]},{"@type":"WebSite","@id":"https:\/\/www.cafbl.cat\/es\/#website","url":"https:\/\/www.cafbl.cat\/es\/","name":"Col\u00b7legi Administradors de Finques Barcelona Lleida","description":"Web oficial del Col\u00b7legi Administradors de Finques Barcelona Lleida","publisher":{"@id":"https:\/\/www.cafbl.cat\/es\/#organization"},"alternateName":"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cafbl.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cafbl.cat\/es\/#organization","name":"Col\u00b7legi Administradors de Finques Barcelona Lleida","alternateName":"CAFBL - Col\u00b7legi Administradors de Finques Barcelona Lleida","url":"https:\/\/www.cafbl.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2024\/07\/logo_cafbl.svg","contentUrl":"https:\/\/www.cafbl.cat\/wp-content\/uploads\/2024\/07\/logo_cafbl.svg","width":471,"height":116,"caption":"Col\u00b7legi Administradors de Finques Barcelona Lleida"},"image":{"@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/CAFbcn_lleida","https:\/\/www.linkedin.com\/company\/administradors-finques-cafbl","https:\/\/www.instagram.com\/administradors_finques_cafbl\/"]},{"@type":"Person","@id":"https:\/\/www.cafbl.cat\/es\/#\/schema\/person\/bfdd3486c3f782e0fd324b2d5a98ef47","name":"adminwpcafbl","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b32455939fe3be4b8b0c3e83865545e13c95024ea445ea7e7e6774d5f0eebe28?s=96&d=mm&r=g","caption":"adminwpcafbl"},"sameAs":["https:\/\/cafbl.cat"],"url":"https:\/\/www.cafbl.cat\/es\/author\/adminwpcafbl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/posts\/153959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/comments?post=153959"}],"version-history":[{"count":0,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/posts\/153959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/media\/96905"}],"wp:attachment":[{"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/media?parent=153959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/categories?post=153959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafbl.cat\/es\/wp-json\/wp\/v2\/tags?post=153959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}